{"id":33870,"date":"2022-06-08T14:26:36","date_gmt":"2022-06-08T12:26:36","guid":{"rendered":"https:\/\/www.locusmap.app\/?p=33870"},"modified":"2022-06-09T13:51:23","modified_gmt":"2022-06-09T11:51:23","slug":"welches-telefon-eignet-sich-am-besten-fuer-locus-map","status":"publish","type":"post","link":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/","title":{"rendered":"Welches Telefon eignet sich am besten f\u00fcr Locus Map?"},"content":{"rendered":"\n<p><\/p>\n\n<p>Diese Frage h\u00f6ren wir recht h\u00e4ufig im Locus-Forum, im Helpdesk und in den sozialen Medien. Welche Parameter sollte es haben? Welcher Speicher, welche Akkulaufzeit, welcher Prozessor? In erster Linie versuchen wir, Locus auf fast allen Ger\u00e4ten zum Laufen zu bringen, da wir nicht viel Einblick in die verf\u00fcgbare Hardware haben. Wir verwenden nur ein paar Dutzend g\u00e4ngige Ger\u00e4te in der Entwicklung und f\u00fcr den normalen Betrieb.<\/p>\n\n<p>Lassen Sie uns dennoch versuchen, ein ideales Modell zu entwerfen, das alle verf\u00fcgbaren Kriterien f\u00fcr die Verwendung mit Locus erf\u00fcllt. Welche Eigenschaften sollte es also haben?<\/p>\n\n<h1 class=\"wp-block-heading\">Langlebigkeit<\/h1>\n\n<p>Locus Map ist in erster Linie als <strong>Navigationsger\u00e4t f\u00fcr Outdoor-Aktivit\u00e4ten<\/strong> gedacht &#8211; Wandern, Mountainbiking, Bergsteigen oder das Durchklettern von Dickichten auf der Suche nach Geocaches. Das Telefon sollte also einiges aushalten k\u00f6nnen &#8211; es sollte sto\u00dffest und einigerma\u00dfen wasserdicht sein, um einen Sturz in den Schlamm oder einen Wolkenbruch unbeschadet zu \u00fcberstehen. Einige Telefone sind direkt f\u00fcr eine h\u00f6here Widerstandsf\u00e4higkeit zertifiziert, und Sie k\u00f6nnen anhand <a href=\"https:\/\/www.digitaltrends.com\/mobile\/what-do-ip-ratings-mean\/\" target=\"_blank\" rel=\"noopener\">dieser Zertifizierung<\/a> erkennen, was das Telefon unbeschadet \u00fcberstehen sollte.<\/p>\n\n<p>Aber es gibt auch viele <strong>Taschen und H\u00fcllen<\/strong> auf dem Markt, die Ihr Lounge-Modell in einen echten Outdoor-Block verwandeln k\u00f6nnen.<\/p>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small.jpg\" data-fancybox><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small-800x600.jpg\" alt=\"\" class=\"wp-image-33857\" srcset=\"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small-800x600.jpg 800w, https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small-600x450.jpg 600w, https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small-768x576.jpg 768w, https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small.jpg 1024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption>Navigieren mit dem Pixel 1 in Bosnien<\/figcaption><\/figure>\n<h1 class=\"wp-block-heading\">Hochwertiges Display<\/h1>\n\n<p>Die grundlegende Kommunikationsschnittstelle von Locus ist <strong>die Karte<\/strong>. Wenn sie unleserlich oder bei direktem Sonnenlicht nicht sichtbar ist, hilft sie nicht viel bei der Orientierung. Wir empfehlen daher, Modelle mit h\u00f6herer Aufl\u00f6sung, h\u00f6herem Kontrast und vor allem h\u00f6herer Display-Helligkeit zu w\u00e4hlen. Diese wird in Einheiten von <a href=\"https:\/\/www.trustedreviews.com\/explainer\/what-is-a-nit-4168293\" target=\"_blank\" rel=\"noopener\">Nits<\/a> oder cd\/m2 angegeben. Viele Hersteller geben diesen Wert f\u00fcr ihre Modelle an, oder er wird von einigen Pr\u00fcfern, wie z. B. <a href=\"https:\/\/www.gsmarena.com\/\" target=\"_blank\" rel=\"noopener\">Gsmarena.com<\/a>, unabh\u00e4ngig gemessen. Denken Sie daran, dass viele Handys die maximale Display-Helligkeit nur nutzen k\u00f6nnen, wenn die Helligkeit auf Auto eingestellt ist. Nat\u00fcrlich schreitet die Entwicklung in diesem Bereich sprunghaft voran &#8211; vergleichen Sie zum Beispiel das sehr hochwertige Display des Samsung S10 mit dem aktuellen S22, der Unterschied ist sehr deutlich.<\/p>\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/news.samsung.com\/global\/how-colors-bring-out-the-best-in-the-galaxy-s10s-dynamic-amoled-display\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/AS_bq6cl18JhC_XNaeAevjMd-y2I9mht1ajzyeG0OX-Ybg5ixCbwHuMzRTsnCdWtMiDhSGDBh1bGzqx1wHeUtrpLunvX1vrnsw0TojnDmY2oOLBRplSYhtg5Bp4wNiQJlGokO4f1cLas31ww0w\" alt=\"\"\/><\/a><\/figure>\n<h1 class=\"wp-block-heading\">Gro\u00dfe Batteriekapazit\u00e4t<\/h1>\n\n<p>Im Allgemeinen verbrauchen das Display, das GPS-Modul und der Prozessor den meisten Strom. Locus Map nutzt sie alle &#8211; das Display zeigt die Karte, Routen und Caches an, GPS und andere Bewegungssensoren erfassen Ihren Standort, Vektorkarten und die Arbeit mit Geodaten besch\u00e4ftigen den Prozessor. Da ist es verst\u00e4ndlich, dass die App bei voller Leistung einen ordentlichen Biss in den Akku hat. <strong>Wir empfehlen daher, sich ein Handy mit einem gr\u00f6\u00dferen Akku zuzulegen oder auf l\u00e4ngeren Touren eine Powerbank mitzunehmen. <\/strong><\/p>\n\n<p>Die Akkukapazit\u00e4t wird in mAh gemessen, und diese Zahl wird von den Herstellern immer in den Spezifikationen des Telefons angegeben. H\u00f6her = besser, aber die Gesamtlebensdauer des Akkus h\u00e4ngt auch von anderen Aspekten wie der Optimierung des Herstellers ab. Auch hier ist es also eine gute Idee, sich an Tester zu halten, die \u00fcber eine etablierte Methode zum Testen der Akkulaufzeit von Handys verf\u00fcgen, damit sie die Modelle miteinander vergleichen k\u00f6nnen.\u00a0<\/p>\n\n<p>Locus Map kann aber auch Strom <strong>sparen<\/strong> &#8211; das Display kann automatisch nur vor Abbiegungen w\u00e4hrend der Navigation eingeschaltet werden, w\u00e4hrend der GPS-Spar-Modus den Standort erst nach einigen Minuten aufzeichnet. Wenn Sie den &#8222;Flugzeug&#8220;-Modus einschalten, kann ein durchschnittliches Telefon einen ganzen Tag lang mit Locus laufen.<\/p>\n\n<h1 class=\"wp-block-heading\">Kompakte Gr\u00f6\u00dfe<\/h1>\n\n<p>Ein kleineres Handy ist weniger anf\u00e4llig f\u00fcr Sch\u00e4den, passt besser auf den Lenker eines Fahrrads und ein kleineres Display &#8222;frisst&#8220; weniger&#8230; Die geringere Gr\u00f6\u00dfe hat unbestreitbar viele Vorteile, leider beg\u00fcnstigen die aktuellen Trends keine kleinen Handys. Die Gesch\u00e4fte sind voll von riesigen &#8222;Pfannkuchen&#8220; mit Sechs-Zoll-Displays, die nicht einmal in die Tasche passen. Und seien wir ehrlich, wir haben uns sehr schnell an gro\u00dfe Displays gew\u00f6hnt, sie sind gut ablesbar, bieten Platz f\u00fcr viele Informationen, eignen sich hervorragend zum Betrachten von Fotos und Videos&#8230; Auf der anderen Seite bedeutet ein kleineres Handy in der Regel auch einen kleineren Akku, siehe den vorherigen Abschnitt. Jeder muss also den richtigen Kompromiss finden.<\/p>\n\n<p>Die Anschaffung eines zweiten, kleineren Telefons kann eine akzeptable L\u00f6sung sein, oder Sie k\u00f6nnen ein \u00e4lteres Modell aus der Schublade fischen. Sie brauchen nicht einmal eine SIM-Karte, Locus kann auch offline laufen.<\/p>\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/IMG_20220608_115505_small.jpg\" data-fancybox><img decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/IMG_20220608_115505_small.jpg\" alt=\"\" class=\"wp-image-33860\" srcset=\"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/IMG_20220608_115505_small.jpg 1024w, https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/IMG_20220608_115505_small-600x338.jpg 600w, https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/IMG_20220608_115505_small-768x433.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption>Cubot KingKong Mini 2 ist eines der kleinsten Handys auf dem Markt<\/figcaption><\/figure>\n<h1 class=\"wp-block-heading\">Hochwertige Sensoren<\/h1>\n\n<p>Jedes Smartphone sammelt mit Hilfe einer Reihe von eingebauten Sensoren Informationen \u00fcber die Welt um es herum. Nat\u00fcrlich ist ein <strong>hochwertiges GNSS-Modul<\/strong> (GNSS = Global Navigation Satellite System) f\u00fcr Locus Map unverzichtbar, das nicht nur Daten aus dem GPS-Netz, sondern auch von anderen Systemen &#8211; Galileo, Glonass oder Chinas Beidou &#8211; empfangen kann. Je mehr Satelliten es ortet, desto genauer ist die Position, die es an Locus sendet. Moderne Telefone der letzten Jahre k\u00f6nnen die Positionsgenauigkeit durch die Verwendung von <a href=\"https:\/\/www.xda-developers.com\/oppo-find-x2-realme-x50-pro-samsung-galaxy-s20-iqoo-3-dual-frequency-gps-gnss\/\" target=\"_blank\" rel=\"noopener\">Multiband-GNSS<\/a> noch einmal deutlich verbessern. Dies ist z. B. f\u00fcr die Navigation in St\u00e4dten n\u00fctzlich, wo die Reflexion des Satellitensignals an Geb\u00e4uden deutlich weniger schwankt.<\/p>\n\n<p>F\u00fcr die Orientierung in den Himmelsrichtungen ist es sinnvoll, einen Hardware-Magnetkompass zu haben (Locus funktioniert auch ohne ihn, aber dann berechnet es die Orientierung nur, wenn es sich anhand von GPS-Daten bewegt). <strong>Vergessen Sie aber nicht, ihn gelegentlich zu <a href=\"https:\/\/docs.locusmap.app\/doku.php?id=manual:faq:how_to_calibrate_compass\" target=\"_blank\" rel=\"noopener\">kalibrieren<\/a>.<\/strong><\/p>\n\n<p>Locus erh\u00e4lt auch H\u00f6heninformationen von GPS, aber dies kann erheblich verbessert werden, wenn das Telefon auch \u00fcber einen <strong>barometrischen H\u00f6henmesser<\/strong> verf\u00fcgt. Dessen Verwendung muss jedoch in den Locus-Einstellungen aktiviert werden.<\/p>\n\n<p>Ein hochwertiger N\u00e4herungssensor ist f\u00fcr die korrekte Bedienung des Bildschirms durch Gesten n\u00fctzlich, aber das ist nur das T\u00fcpfelchen auf dem i.<\/p>\n\n<h1 class=\"wp-block-heading\">Konnektivit\u00e4t<\/h1>\n\n<p>Locus Map kann mit vielen externen Sensoren kommunizieren &#8211; Herzfrequenz-, Geschwindigkeits-, Trittfrequenz- und Leistungssensoren, Thermometer, etc. Sowohl Bluetooth als auch ANT+ werden unterst\u00fctzt. Bluetooth ist ein Standardmerkmal aller Smartphones. Schlechter sieht es bei ANT+ aus, das sich leider auf dem Weg aus dem technologischen Rampenlicht befindet. Die Hersteller geben oft nicht einmal mehr in den Spezifikationen der einzelnen Modelle an, ob ANT installiert ist, so dass wir uns nur auf die Liste der offiziell unterst\u00fctzten Ger\u00e4te auf der Website <a href=\"http:\/\/www.thisisant.com\/\" target=\"_blank\" rel=\"noopener\">www.thisisant.com<\/a> verlassen k\u00f6nnen. Diese Liste wird leider nicht mehr sehr umfangreich. Gl\u00fccklicherweise werden immer mehr Sensoren angeboten, die die neuesten Bluetooth-Standards unterst\u00fctzen.<\/p>\n\n<p>Wenn Sie jedoch nicht aktiv Daten \u00fcber Ihre sportliche Leistung sammeln und nur zum Spa\u00df im Freien sind, k\u00f6nnen Sie diesen Parameter getrost weglassen.<\/p>\n\n<h1 class=\"wp-block-heading\">Leistung<\/h1>\n\n<p>Sie k\u00f6nnen Locus Map auch auf einem \u00e4lteren Android 5 Handy (dem \u00e4ltesten unterst\u00fctzten Betriebssystem) betreiben, aber seien wir ehrlich, auf dem neuesten Octa-Core mit 16 GB RAM macht es etwas mehr Spa\u00df &#8211; Sie k\u00f6nnen Dutzende von Routen und Tausende von Caches auf der Karte betrachten, ohne dass es zu Verz\u00f6gerungen kommt, Karten-Overlays bequem nutzen oder gro\u00dfe KMZ-Dateien importieren. Aber wenn Sie lernen, klug mit der Energie umzugehen, braucht Locus Map keine zus\u00e4tzliche &#8222;Kanone&#8220;.<\/p>\n\n<p>Sie k\u00f6nnen sich eine Menge \u00c4rger ersparen, wenn Sie ein Modell mit einer &#8222;sauberen&#8220; Version des Android-Betriebssystems w\u00e4hlen. Verschiedene Add-ons, vor allem von chinesischen Herstellern, enthalten oft eine Batteriesparsoftware, die Locus Map in den besten Einstellungen dann ausschaltet, wenn Sie es am wenigsten brauchen &#8211; beim Aufzeichnen eines Tracks oder beim Navigieren.<\/p>\n\n<h1 class=\"wp-block-heading\">Welche Telefone benutzen wir?<\/h1>\n\n<p>Wir haben ein wenig im Team recherchiert: Der Entwickler-Teil bevorzugt Modelle mit reinem Android, also Pixel aller m\u00f6glichen Generationen vom archaischen Pixel 1 bis zum Pixel 5, und es g\u00e4be auch einige Nokia-Ger\u00e4te. Der Support-Bereich hat chinesische Telefone Xiaomi, Honor und OnePlus, da diese die meisten Probleme verursachen, die h\u00e4ufig getestet werden m\u00fcssen. Wir haben kleine oder \u00e4ltere Handys auf dem Rad &#8211; zum Beispiel das kleine und robuste <a href=\"https:\/\/www.amazon.de\/dp\/B08PCMNRTH\/\" target=\"_blank\" rel=\"noopener\">Cubot KingKong Mini 2<\/a> oder, unter den \u00e4lteren, das legend\u00e4re HTC One Mini 2 aus Aluminium oder das Samsung S7. Aber einige unserer Nutzer gehen in ihren <a href=\"https:\/\/www.facebook.com\/photo.php?fbid=10225306909715670&amp;set=gm.953891071848177&amp;type=3&amp;theater\" target=\"_blank\" rel=\"noopener\">Experimenten<\/a> noch viel weiter \ud83d\ude42<\/p>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20220603_161741_small.jpg\" data-fancybox><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20220603_161741_small-800x600.jpg\" alt=\"\" class=\"wp-image-33863\" srcset=\"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20220603_161741_small-800x600.jpg 800w, https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20220603_161741_small-600x450.jpg 600w, https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20220603_161741_small-768x576.jpg 768w, https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20220603_161741_small.jpg 1024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption>Das gute alte Samsung S7 ist immer noch in Aktion<\/figcaption><\/figure>\n<p>Im Sinne eines verantwortungsvollen Umgangs mit der Umwelt ist es am besten, einfach das Telefon zu benutzen, das Sie bereits haben, oder zum Spa\u00df ein altes, nicht mehr benutztes aus der Schublade zu holen. Betrachten Sie diesen Artikel also einfach als eine Reihe von Empfehlungen, welche Funktionen Ihrer Hardware Sie \u00fcberwachen sollten. <\/p>\n\n<h2 class=\"wp-block-heading\">Wir w\u00fcnschen Ihnen viel Spa\u00df mit Locus Map, egal, wof\u00fcr Sie es verwenden!\u00a0<\/h2>\n<div class=\"clearfix\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Diese Frage h\u00f6ren wir recht h\u00e4ufig im Locus-Forum, im Helpdesk und in den sozialen Medien&#8230;.<\/p>\n","protected":false},"author":6,"featured_media":33857,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[298],"tags":[3925,3923,3924],"class_list":["post-33870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tech","tag-best-of","tag-mobile","tag-phone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Welches Telefon eignet sich am besten f\u00fcr Locus Map?<\/title>\n<meta name=\"description\" content=\"Jedes Smartphone mit einem Android-Betriebssystem, das neuer als 5 ist, ist geeignet, aber hier sind ein paar Empfehlungen, auf welche Funktionen Sie sich konzentrieren sollten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Welches Telefon eignet sich am besten f\u00fcr Locus Map?\" \/>\n<meta property=\"og:description\" content=\"Jedes Smartphone mit einem Android-Betriebssystem, das neuer als 5 ist, ist geeignet, aber hier sind ein paar Empfehlungen, auf welche Funktionen Sie sich konzentrieren sollten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/\" \/>\n<meta property=\"og:site_name\" content=\"Locus Map - Outdoor-Navigations-App\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/locusmap\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-08T12:26:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-09T11:51:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michal, Locus team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michal, Locus team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/\"},\"author\":{\"name\":\"Michal, Locus team\",\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/#\\\/schema\\\/person\\\/f2818553504c96f669f4559aa039de39\"},\"headline\":\"Welches Telefon eignet sich am besten f\u00fcr Locus Map?\",\"datePublished\":\"2022-06-08T12:26:36+00:00\",\"dateModified\":\"2022-06-09T11:51:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/\"},\"wordCount\":1403,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.locusmap.app\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/20210928_182744_small.jpg\",\"keywords\":[\"best of\",\"mobile\",\"phone\"],\"articleSection\":[\"Tech\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/\",\"url\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/\",\"name\":\"Welches Telefon eignet sich am besten f\u00fcr Locus Map?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.locusmap.app\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/20210928_182744_small.jpg\",\"datePublished\":\"2022-06-08T12:26:36+00:00\",\"dateModified\":\"2022-06-09T11:51:23+00:00\",\"description\":\"Jedes Smartphone mit einem Android-Betriebssystem, das neuer als 5 ist, ist geeignet, aber hier sind ein paar Empfehlungen, auf welche Funktionen Sie sich konzentrieren sollten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.locusmap.app\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/20210928_182744_small.jpg\",\"contentUrl\":\"https:\\\/\\\/www.locusmap.app\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/20210928_182744_small.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Welches Telefon eignet sich am besten f\u00fcr Locus Map?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/\",\"name\":\"Locus Map - Outdoor-Navigations-App\",\"description\":\"Multifunktionale mobile Outdoor-Navigations-App zum Wandern, Radfahren, Geocaching, Segeln, Fliegen und f\u00fcr andere Sport- und Reiseaktivit\u00e4ten\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/#organization\",\"name\":\"Locus Map - mobile outdoor navigation app\",\"url\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.locusmap.app\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ggplay-screen-lm4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.locusmap.app\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ggplay-screen-lm4.jpg\",\"width\":1024,\"height\":500,\"caption\":\"Locus Map - mobile outdoor navigation app\"},\"image\":{\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/locusmap\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Locus_Map\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.locusmap.app\\\/de\\\/#\\\/schema\\\/person\\\/f2818553504c96f669f4559aa039de39\",\"name\":\"Michal, Locus team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d19c69208f6219eb7200025f8cf6410c304c904a0978cc3674fe34a9c8e6d300?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d19c69208f6219eb7200025f8cf6410c304c904a0978cc3674fe34a9c8e6d300?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d19c69208f6219eb7200025f8cf6410c304c904a0978cc3674fe34a9c8e6d300?s=96&d=mm&r=g\",\"caption\":\"Michal, Locus team\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Welches Telefon eignet sich am besten f\u00fcr Locus Map?","description":"Jedes Smartphone mit einem Android-Betriebssystem, das neuer als 5 ist, ist geeignet, aber hier sind ein paar Empfehlungen, auf welche Funktionen Sie sich konzentrieren sollten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/","og_locale":"de_DE","og_type":"article","og_title":"Welches Telefon eignet sich am besten f\u00fcr Locus Map?","og_description":"Jedes Smartphone mit einem Android-Betriebssystem, das neuer als 5 ist, ist geeignet, aber hier sind ein paar Empfehlungen, auf welche Funktionen Sie sich konzentrieren sollten.","og_url":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/","og_site_name":"Locus Map - Outdoor-Navigations-App","article_publisher":"https:\/\/www.facebook.com\/locusmap","article_published_time":"2022-06-08T12:26:36+00:00","article_modified_time":"2022-06-09T11:51:23+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small.jpg","type":"image\/jpeg"}],"author":"Michal, Locus team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Michal, Locus team","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/#article","isPartOf":{"@id":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/"},"author":{"name":"Michal, Locus team","@id":"https:\/\/www.locusmap.app\/de\/#\/schema\/person\/f2818553504c96f669f4559aa039de39"},"headline":"Welches Telefon eignet sich am besten f\u00fcr Locus Map?","datePublished":"2022-06-08T12:26:36+00:00","dateModified":"2022-06-09T11:51:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/"},"wordCount":1403,"commentCount":0,"publisher":{"@id":"https:\/\/www.locusmap.app\/de\/#organization"},"image":{"@id":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/#primaryimage"},"thumbnailUrl":"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small.jpg","keywords":["best of","mobile","phone"],"articleSection":["Tech"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/","url":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/","name":"Welches Telefon eignet sich am besten f\u00fcr Locus Map?","isPartOf":{"@id":"https:\/\/www.locusmap.app\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/#primaryimage"},"image":{"@id":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/#primaryimage"},"thumbnailUrl":"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small.jpg","datePublished":"2022-06-08T12:26:36+00:00","dateModified":"2022-06-09T11:51:23+00:00","description":"Jedes Smartphone mit einem Android-Betriebssystem, das neuer als 5 ist, ist geeignet, aber hier sind ein paar Empfehlungen, auf welche Funktionen Sie sich konzentrieren sollten.","breadcrumb":{"@id":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/#primaryimage","url":"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small.jpg","contentUrl":"https:\/\/www.locusmap.app\/wp-content\/uploads\/2022\/06\/20210928_182744_small.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.locusmap.app\/de\/welches-telefon-eignet-sich-am-besten-fuer-locus-map\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/www.locusmap.app\/de\/"},{"@type":"ListItem","position":2,"name":"Welches Telefon eignet sich am besten f\u00fcr Locus Map?"}]},{"@type":"WebSite","@id":"https:\/\/www.locusmap.app\/de\/#website","url":"https:\/\/www.locusmap.app\/de\/","name":"Locus Map - Outdoor-Navigations-App","description":"Multifunktionale mobile Outdoor-Navigations-App zum Wandern, Radfahren, Geocaching, Segeln, Fliegen und f\u00fcr andere Sport- und Reiseaktivit\u00e4ten","publisher":{"@id":"https:\/\/www.locusmap.app\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.locusmap.app\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.locusmap.app\/de\/#organization","name":"Locus Map - mobile outdoor navigation app","url":"https:\/\/www.locusmap.app\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.locusmap.app\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.locusmap.app\/wp-content\/uploads\/2021\/03\/ggplay-screen-lm4.jpg","contentUrl":"https:\/\/www.locusmap.app\/wp-content\/uploads\/2021\/03\/ggplay-screen-lm4.jpg","width":1024,"height":500,"caption":"Locus Map - mobile outdoor navigation app"},"image":{"@id":"https:\/\/www.locusmap.app\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/locusmap","https:\/\/en.wikipedia.org\/wiki\/Locus_Map"]},{"@type":"Person","@id":"https:\/\/www.locusmap.app\/de\/#\/schema\/person\/f2818553504c96f669f4559aa039de39","name":"Michal, Locus team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d19c69208f6219eb7200025f8cf6410c304c904a0978cc3674fe34a9c8e6d300?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d19c69208f6219eb7200025f8cf6410c304c904a0978cc3674fe34a9c8e6d300?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d19c69208f6219eb7200025f8cf6410c304c904a0978cc3674fe34a9c8e6d300?s=96&d=mm&r=g","caption":"Michal, Locus team"}}]}},"_links":{"self":[{"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/posts\/33870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/comments?post=33870"}],"version-history":[{"count":7,"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/posts\/33870\/revisions"}],"predecessor-version":[{"id":33884,"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/posts\/33870\/revisions\/33884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/media\/33857"}],"wp:attachment":[{"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/media?parent=33870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/categories?post=33870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locusmap.app\/de\/wp-json\/wp\/v2\/tags?post=33870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}